{"id":49512,"date":"2025-09-19T14:32:44","date_gmt":"2025-09-19T05:32:44","guid":{"rendered":"https:\/\/eatsjapan.com\/?post_type=product&#038;p=49512"},"modified":"2026-02-06T16:17:33","modified_gmt":"2026-02-06T07:17:33","slug":"atagawa-banana-crocodile-ball-chain-vol2","status":"publish","type":"product","link":"https:\/\/eatsjapan.com\/de\/products\/atagawa-banana-crocodile-ball-chain-vol2\/","title":{"rendered":"Atagawa Banane Krokodil Kugelkette Vol.2"},"content":{"rendered":"<p><span class=\"ttldesc\">Probieren Sie es aus!<span><\/p>\n<p>Willst du sie alle sammeln? Mit dem Komplettset k\u00f6nnen Sie garantiert jedes Design genie\u00dfen!<br \/>\nJedes Kapselspielzeug ist immer noch eine wunderbare \u00dcberraschung, und du wirst nicht wissen, welches niedliche oder schrullige Design du bekommst, bis du es \u00f6ffnest - so wird jedes \u00d6ffnen zu einem kleinen Abenteuer f\u00fcr dein Herz!<br \/>\nManche Gegenst\u00e4nde sind schwieriger zu finden und machen Ihre Sammlung noch spannender.<br \/>\nStellen Sie sie in einer Reihe auf, um die gesamte Serie zu vervollst\u00e4ndigen, und sp\u00fcren Sie die Zufriedenheit und den einzigartigen Charme, die Ihren Alltag bereichern!<br \/>\nHolen Sie sich noch heute ein St\u00fcck der ber\u00fchmten japanischen Kapselspielzeugkultur nach Hause.<br \/>\nStarten Sie Ihre Sammlung, genie\u00dfen Sie die \u00dcberraschungen und lassen Sie den Spa\u00df mit jeder Kapsel weiter wachsen!<\/p>","protected":false},"excerpt":{"rendered":"<p>Atagawa Banana Crocodile Park Daifuku Croc Ball Chain Vol.2 bringt matschigen Sammelspa\u00df! Winzige Krokodile baumeln entz\u00fcckend f\u00fcr ein spielerisches Display-Abenteuer.<\/p>\n<p><span class=\"collectionttl\">Sammlung<\/span><br \/>\n\u30fbDaifuku Krokodil: Banane\u30fbDaifuku Krokodil: Kirsche\u30fbDaifuku Wei\u00dfes Krokodil: Erdbeere\u30fbDaifuku Krokodil: Muskat\u30fbDaifuku Krokodil: Mandarine Orange<\/p>","protected":false},"featured_media":49397,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[338,341,293],"product_tag":[307],"class_list":["post-49512","product","type-product","status-publish","has-post-thumbnail","product_cat-animal-pet-toys","product_cat-complete-sets","product_cat-gacha","product_tag-end-of-sale","first","outofstock","sale","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"_links":{"self":[{"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/product\/49512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/comments?post=49512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/media\/49397"}],"wp:attachment":[{"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/media?parent=49512"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/product_brand?post=49512"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/product_cat?post=49512"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/product_tag?post=49512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}