{"id":49478,"date":"2025-10-07T08:40:38","date_gmt":"2025-10-06T23:40:38","guid":{"rendered":"https:\/\/eatsjapan.com\/?post_type=product&#038;p=49478"},"modified":"2026-02-06T16:17:01","modified_gmt":"2026-02-06T07:17:01","slug":"babybus-costume-plush-mascot","status":"publish","type":"product","link":"https:\/\/eatsjapan.com\/de\/products\/babybus-costume-plush-mascot\/","title":{"rendered":"BabyBus Kost\u00fcm Pl\u00fcsch Maskottchen"},"content":{"rendered":"<p><span class=\"ttldesc\">Probieren Sie es aus!<span><\/p>\n<p>Willst du sie alle sammeln? Mit dem Komplettset k\u00f6nnen Sie garantiert jedes Design genie\u00dfen!<br \/>\nJedes Kapselspielzeug ist immer noch eine wunderbare \u00dcberraschung, und du wirst nicht wissen, welches niedliche oder schrullige Design du bekommst, bis du es \u00f6ffnest - so wird jedes \u00d6ffnen zu einem kleinen Abenteuer f\u00fcr dein Herz!<br \/>\nManche Gegenst\u00e4nde sind schwieriger zu finden und machen Ihre Sammlung noch spannender.<br \/>\nStellen Sie sie in einer Reihe auf, um die gesamte Serie zu vervollst\u00e4ndigen, und sp\u00fcren Sie die Zufriedenheit und den einzigartigen Charme, die Ihren Alltag bereichern!<br \/>\nHolen Sie sich noch heute ein St\u00fcck der ber\u00fchmten japanischen Kapselspielzeugkultur nach Hause.<br \/>\nStarten Sie Ihre Sammlung, genie\u00dfen Sie die \u00dcberraschungen und lassen Sie den Spa\u00df mit jeder Kapsel weiter wachsen!<\/p>","protected":false},"excerpt":{"rendered":"<p>Verkleidungsspa\u00df zum Mitnehmen! Mit dem BabyBus Kost\u00fcm Pl\u00fcschmaskottchen k\u00f6nnen kleine Charaktere jederzeit und \u00fcberall lustige Outfits tragen und niedliche Abenteuer im Taschenformat erleben!<\/p>\n<p><span class=\"collectionttl\">Sammlung<\/span><br \/>\nKiki\u30fbMiu Miu\u30fbEinfarbiger Doughnut\u30fbRoter Doughnut\u30fbGelber Doughnut<\/p>","protected":false},"featured_media":49400,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[338,341,334,293],"product_tag":[307],"class_list":["post-49478","product","type-product","status-publish","has-post-thumbnail","product_cat-animal-pet-toys","product_cat-complete-sets","product_cat-cute-kawaii-toys","product_cat-gacha","product_tag-end-of-sale","first","outofstock","sale","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"_links":{"self":[{"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/product\/49478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/comments?post=49478"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/media\/49400"}],"wp:attachment":[{"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/media?parent=49478"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/product_brand?post=49478"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/product_cat?post=49478"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eatsjapan.com\/de\/wp-json\/wp\/v2\/product_tag?post=49478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}